{"id":147,"date":"2017-07-07T21:18:00","date_gmt":"2017-07-07T20:18:00","guid":{"rendered":"http:\/\/www.jassuremonvelo.com\/blog\/?p=147"},"modified":"2017-07-07T21:18:19","modified_gmt":"2017-07-07T20:18:19","slug":"pourquoi-assurer-un-velo","status":"publish","type":"post","link":"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/","title":{"rendered":"Pourquoi assurer un v\u00e9lo ?"},"content":{"rendered":"<p style=\"text-align: justify;\">Chaque ann\u00e9e, en France, les victimes d\u2019un accident \u00e0 v\u00e9lo se comptent par milliers (4\u00a0000\u00a0personnes). Un chiffre \u00e0 multiplier par 100 pour obtenir le nombre des v\u00e9los vol\u00e9s annuellement. Ces deux \u00e9l\u00e9ments suffisent \u00e0 eux seuls pour expliquer le besoin d\u2019assurer un v\u00e9lo.<!--more--><\/p>\n<p style=\"text-align: justify;\">Pour avoir l\u2019esprit tranquille, cette option est de mise, quel que soit le mode d\u2019utilisation (cycliste du dimanche ou cycliste \u00e0 plein temps). Ces derniers temps, il est m\u00eame possible de personnaliser son contrat selon ce param\u00e8tre-cl\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">Quelques raisons d\u2019assurer son v\u00e9lo<\/h2>\n<p style=\"text-align: justify;\">La raison la plus \u00e9vidente d\u2019assurer un v\u00e9lo est certainement la multiplication des risques de vol. Beaucoup de cyclistes se contentent pourtant d\u2019investir dans un cadenas plut\u00f4t que de recourir \u00e0 cette option. Pourtant, les voleurs disposent de tout un arsenal d\u2019outils leur permettant de pulv\u00e9riser cet accessoire de s\u00e9curit\u00e9, aussi sophistiqu\u00e9 soit-il. Assurer un v\u00e9lo permet aussi de se pr\u00e9munir des impr\u00e9vus. M\u00eame les meilleurs \u00e9l\u00e8ves en mati\u00e8re de s\u00e9curit\u00e9 n\u2019en sont pas \u00e9pargn\u00e9s. Ils sont constamment expos\u00e9s \u00e0 la b\u00eatise d&rsquo;autrui, le plus souvent source de dommages \u00e0 la propri\u00e9t\u00e9. Une autre raison\u00a0: une assurance habitation ne couvre pas forc\u00e9ment un v\u00e9lo. Dans les meilleurs des cas, ce moyen de d\u00e9placement tendance fait l\u2019objet d\u2019un certain nombre de points d\u2019exclusion.<\/p>\n<h2 style=\"text-align: justify;\">L\u2019aspect incontournable d\u2019une assurance v\u00e9lo<\/h2>\n<p style=\"text-align: justify;\">Une assurance v\u00e9lo est d\u2019autant plus indispensable qu\u2019une bicyclette co\u00fbte cher. En cas de vol, le propri\u00e9taire sera couvert par une garantie lui \u00e9vitant de se payer un nouveau v\u00e9lo. La garantie prenant en charge les dommages \u00e0 la propri\u00e9t\u00e9 le met \u00e9galement \u00e0 l\u2019abri des co\u00fbts li\u00e9s aux erreurs d\u2019autrui. Il est, par la suite, possible d\u2019\u00e9tendre la couverture avec des garanties suppl\u00e9mentaires. Enfin, une assurance v\u00e9lo prend en charge d\u2019autres \u00e9l\u00e9ments, comme les pi\u00e8ces de rechange ou certains accessoires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque ann\u00e9e, en France, les victimes d\u2019un accident \u00e0 v\u00e9lo se comptent par milliers (4\u00a0000\u00a0personnes). Un chiffre \u00e0 multiplier par 100 pour obtenir le nombre des v\u00e9los vol\u00e9s annuellement. Ces deux \u00e9l\u00e9ments suffisent \u00e0 eux seuls pour expliquer le besoin d\u2019assurer un v\u00e9lo.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pourquoi assurer un v\u00e9lo ? - Jassuremonvelo - assurance pour v\u00e9lo<\/title>\n<meta name=\"description\" content=\"Bonnes raisons pour assurer un v\u00e9lo de valeur via une assurance v\u00e9lo de qualit\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pourquoi assurer un v\u00e9lo ? - Jassuremonvelo - assurance pour v\u00e9lo\" \/>\n<meta property=\"og:description\" content=\"Bonnes raisons pour assurer un v\u00e9lo de valeur via une assurance v\u00e9lo de qualit\u00e9\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/\" \/>\n<meta property=\"og:site_name\" content=\"Jassuremonvelo - assurance pour v\u00e9lo\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-07T20:18:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-07T20:18:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.jassuremonvelo.com\/blog\/#website\",\"url\":\"http:\/\/www.jassuremonvelo.com\/blog\/\",\"name\":\"Jassuremonvelo - assurance pour v\u00e9lo\",\"description\":\"P\u00e9dalez en toute tranquilit\u00e9 avec Jassuremonvelo.com !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.jassuremonvelo.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/#webpage\",\"url\":\"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/\",\"name\":\"Pourquoi assurer un v\u00e9lo ? - Jassuremonvelo - assurance pour v\u00e9lo\",\"isPartOf\":{\"@id\":\"http:\/\/www.jassuremonvelo.com\/blog\/#website\"},\"datePublished\":\"2017-07-07T20:18:00+00:00\",\"dateModified\":\"2017-07-07T20:18:19+00:00\",\"author\":{\"@id\":\"http:\/\/www.jassuremonvelo.com\/blog\/#\/schema\/person\/abc23e13c4d7eb901089ae5128bf8bbe\"},\"description\":\"Bonnes raisons pour assurer un v\u00e9lo de valeur via une assurance v\u00e9lo de qualit\u00e9\",\"breadcrumb\":{\"@id\":\"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/www.jassuremonvelo.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pourquoi assurer un v\u00e9lo ?\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.jassuremonvelo.com\/blog\/#\/schema\/person\/abc23e13c4d7eb901089ae5128bf8bbe\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.jassuremonvelo.com\/blog\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/51fab509843e146ad026c00b1b0c77eb?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/51fab509843e146ad026c00b1b0c77eb?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"http:\/\/www.jassuremonvelo.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pourquoi assurer un v\u00e9lo ? - Jassuremonvelo - assurance pour v\u00e9lo","description":"Bonnes raisons pour assurer un v\u00e9lo de valeur via une assurance v\u00e9lo de qualit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/","og_locale":"fr_FR","og_type":"article","og_title":"Pourquoi assurer un v\u00e9lo ? - Jassuremonvelo - assurance pour v\u00e9lo","og_description":"Bonnes raisons pour assurer un v\u00e9lo de valeur via une assurance v\u00e9lo de qualit\u00e9","og_url":"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/","og_site_name":"Jassuremonvelo - assurance pour v\u00e9lo","article_published_time":"2017-07-07T20:18:00+00:00","article_modified_time":"2017-07-07T20:18:19+00:00","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/www.jassuremonvelo.com\/blog\/#website","url":"http:\/\/www.jassuremonvelo.com\/blog\/","name":"Jassuremonvelo - assurance pour v\u00e9lo","description":"P\u00e9dalez en toute tranquilit\u00e9 avec Jassuremonvelo.com !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.jassuremonvelo.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/#webpage","url":"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/","name":"Pourquoi assurer un v\u00e9lo ? - Jassuremonvelo - assurance pour v\u00e9lo","isPartOf":{"@id":"http:\/\/www.jassuremonvelo.com\/blog\/#website"},"datePublished":"2017-07-07T20:18:00+00:00","dateModified":"2017-07-07T20:18:19+00:00","author":{"@id":"http:\/\/www.jassuremonvelo.com\/blog\/#\/schema\/person\/abc23e13c4d7eb901089ae5128bf8bbe"},"description":"Bonnes raisons pour assurer un v\u00e9lo de valeur via une assurance v\u00e9lo de qualit\u00e9","breadcrumb":{"@id":"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.jassuremonvelo.com\/blog\/pourquoi-assurer-un-velo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.jassuremonvelo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pourquoi assurer un v\u00e9lo ?"}]},{"@type":"Person","@id":"http:\/\/www.jassuremonvelo.com\/blog\/#\/schema\/person\/abc23e13c4d7eb901089ae5128bf8bbe","name":"admin","image":{"@type":"ImageObject","@id":"http:\/\/www.jassuremonvelo.com\/blog\/#personlogo","inLanguage":"fr-FR","url":"http:\/\/2.gravatar.com\/avatar\/51fab509843e146ad026c00b1b0c77eb?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/51fab509843e146ad026c00b1b0c77eb?s=96&d=mm&r=g","caption":"admin"},"url":"http:\/\/www.jassuremonvelo.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/posts\/147"}],"collection":[{"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/comments?post=147"}],"version-history":[{"count":2,"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/posts\/147\/revisions"}],"predecessor-version":[{"id":149,"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/posts\/147\/revisions\/149"}],"wp:attachment":[{"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/media?parent=147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/categories?post=147"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jassuremonvelo.com\/blog\/wp-json\/wp\/v2\/tags?post=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}